{"id":14276,"date":"2026-02-26T04:19:59","date_gmt":"2026-02-26T03:19:59","guid":{"rendered":"https:\/\/rowermax.shop\/ro64\/produkt\/kross-esker-7-0-rozmiar-xl-22-bialy-perlowy\/"},"modified":"2026-02-26T04:20:02","modified_gmt":"2026-02-26T03:20:02","slug":"kross-esker-7-0-rozmiar-xl-22-bialy-perlowy","status":"publish","type":"product","link":"https:\/\/xavlino.shop\/ro64\/produkt\/kross-esker-7-0-rozmiar-xl-22-bialy-perlowy\/","title":{"rendered":"Kross Esker 7.0 rozmiar XL 22&quot; bia\u0142y per\u0142owy"},"content":{"rendered":"<div style=\"font-family: Arial, sans-serif; line-height: 1.6; color: #333; padding: 20px; clear: both; display: block; width: 100%; float: none; position: static; overflow: hidden;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h2>Rower Gravel Kross Esker 7.0 Per\u0142owy\/Br\u0105zowy Po\u0142ysk &#8211; XL 22<\/h2>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Kross<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Rowery gravelowe Kross to wszechstronne jedno\u015blady stworzone do pokonywania zar\u00f3wno asfaltowych dr\u00f3g, jak i trudniejszych nawierzchni terenowych. Dzi\u0119ki specjalnie zaprojektowanym ramom gravele Kross \u0142\u0105cz\u0105 komfort jazdy na d\u0142u\u017cszych trasach z mo\u017cliwo\u015bci\u0105 eksploracji mniej utwardzonych \u015bcie\u017cek, zapewniaj\u0105c rowerzystom wyj\u0105tkow\u0105 swobod\u0119 i dostosowanie do r\u00f3\u017cnorodnych warunk\u00f3w.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">KROSS ESKER 7.0<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">KROSS Esker 7.0 to rower gravelowy, kt\u00f3ry otworzy przed Tob\u0105 zupe\u0142nie nowe mo\u017cliwo\u015bci. Rama i widelec wykonane z carbonu oferuj\u0105 niezr\u00f3wnane po\u0142\u0105czenie lekko\u015bci i wytrzyma\u0142o\u015bci. Nap\u0119d Shimano GRX w systemie 1&#215;12 oraz hydrauliczne hamulce tarczowe sprawi\u0105, \u017ce zyskasz pe\u0142n\u0105 kontrol\u0119 na ka\u017cdym szlaku \u2013 zar\u00f3wno na szybkich asfaltowych odcinkach, jak i na wymagaj\u0105cych drogach szutrowych.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wysokiej klasy osprz\u0119t<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">KROSS Esker 7.0 zosta\u0142 wyposa\u017cony w osprz\u0119t Shimano, kt\u00f3ry doskonale sprawdzi si\u0119 zar\u00f3wno na asfalcie, jak i w terenie. Zastosowali\u015bmy sprawdzony nap\u0119d w systemie 1&#215;12, kt\u00f3ry umo\u017cliwi komfortow\u0105 jazd\u0119 w ka\u017cdych warunkach. Kaseta w zakresie 10-51 sprawi, \u017ce pojedziesz szybko po p\u0142askim i bez problemu pokonasz strome wzniesienia.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">By zapewni\u0107 pewno\u015b\u0107 hamowania w ka\u017cdych warunkach zamontowane zosta\u0142y hydrauliczne hamulce tarczowe Shimano. Zapewniaj\u0105 one du\u017c\u0105 wi\u0119ksz\u0105 si\u0142\u0119 hamowania ni\u017c klasyczne hamulce v-brake. To tak\u017ce du\u017co wi\u0119ksza i precyzyjniejsza modulacja si\u0142y hamowania ni\u017c w przypadku mechanicznych hamulc\u00f3w tarczowych.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Technologie zapewniaj\u0105ce zabaw\u0119 z dala od cywilizacji<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Rama oraz widelec KROSS Esker zosta\u0142y wykonane z carbonu. Carbon, znany tak\u017ce jako w\u0142\u00f3kno w\u0119glowe, jest bardzo lekki, co przek\u0142ada si\u0119 na wygod\u0119 i \u0142atwo\u015b\u0107 manewrowania podczas ka\u017cdej przeja\u017cd\u017cki. Dzi\u0119ki zastosowaniu tego materia\u0142u otrzymali\u015bmy ram\u0119 oraz widelec, kt\u00f3re charakteryzuj\u0105 si\u0119 wyj\u0105tkow\u0105 sztywno\u015bci\u0105 przy jednoczesnym, doskona\u0142ym poch\u0142anianiu drga\u0144.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Przy projektowaniu ramy postanowili\u015bmy wyposa\u017cy\u0107 j\u0105 w wewn\u0119trzne prowadzenie linek, dzi\u0119ku czemu rower wygl\u0105da estetycznie i schludnie. Ten system prowadzenia linek pozwoli\u0142 nam tak\u017ce na zmniejszenie ryzyka zerwania linki w trakcie jazdy w trudnym terenie.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Aby zapewni\u0107 najlepsze wra\u017cenia z jazdy, KROSS Esker 7.0 zosta\u0142 wyposa\u017cony w opony Schwalbe o szeroko\u015bci 45 mm, kt\u00f3re doskonale sprawdz\u0105 si\u0119 w ka\u017cdych warunkach. Do tego dochodzi zaprojektowane z my\u015bl\u0105 o rowerach szutrowych siod\u0142o oraz owijka Fizik, gwarantuj\u0105ce komfort jazdy nawet podczas trudniejszych tras.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Rozmiar damski czy m\u0119ski?<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wybrane modele KROSS wyst\u0119puj\u0105 w wersjach damskich i m\u0119skich. Jak odr\u00f3\u017cni\u0107 te wersje? Damskie rozmiary\/ramy wyr\u00f3\u017cnione s\u0105 w tabeli doboru ramy (\u201eJak dobra\u0107 rozmiar ramy&#8221;) liter\u0105 \u201eD&#8221; poprzedzaj\u0105c\u0105 liter\u0119 z rozmiarem i tak np. DM (17\u00b4) 28&#8243; oznacza rower dla Pa\u0144 w rozmiarze M przy wielko\u015bci ramy 17 oraz k\u00f3\u0142 28 cali. Rozmiary bez poprzedzaj\u0105cej litery \u201eD&#8221; zwykle oznaczaj\u0105 rozmiar m\u0119ski lub (w zale\u017cno\u015bci od modelu) uniwersalny (np. modele MTB\/MTB XC i inne)<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Jak czyta\u0107 tabele z geometri\u0105 ram?<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">M (19\u00b4) 29&#8243; \u2013 taki zapis oznacza: M \u2013 rozmiar ramy wyra\u017cony symbolem, 19\u00b4 \u2013 rozmiar ramy w calach, a warto\u015b\u0107 29&#8243; oznacza \u015brednic\u0119 ko\u0142a (obr\u0119czy, opony, d\u0119tki) wyra\u017con\u0105 w tak\u017ce w calach (zwykle 26, 27,5 oraz 29 cali dla rower\u00f3w typu MTB oraz 28 cali dla trekkingowych, miejskich, czy szosowych)<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Rama i widelec<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">MATERIA\u0141 RAMY CARBON<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">WIDELEC CARBON<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">SKOK WIDELCA BRAK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">TYLNY AMORTYZATOR BRAK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">SKOK TYLNEGO AMORTYZATORA BRAK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wyko\u0144czenie lakieru po\u0142ysk<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">KOLOR RAMY per\u0142owy<\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Nap\u0119d<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">PRZERZUTKA PRZ\u00d3D BRAK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">PRZERZUTKA TY\u0141 SHIMANO GRX RX822<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">MANETKI SHIMANO GRX RX610<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">KORBA SHIMANO GRX RX610<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">KORONKI 40T (S &#8211; 170MM; M &#8211; 172,5MM; L, XL &#8211; 175MM)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">KASETA \/ WOLNOBIEG SHIMANO SLX M7100<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">ZAKRES KASETY\/WOLNOBIEGU 10-51T<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">ILO\u015a\u0106 PRZE\u0141O\u017bE\u0143 12<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">SUPORT SHIMANO SLX M7100<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">\u0141A\u0143CUCH SHIMANO M7100<\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Ko\u0142a<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">PIASTA PRZ\u00d3D SHIMANO 12&#215;100 TA<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">PIASTA TY\u0141 SHIMANO 12&#215;142 MS TA<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">OBR\u0118CZE DT SWISS G 540 622X24<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">OPONY SCHWALBE G-ONE 700X45C<\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Hamulce<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">HAMULEC PRZ\u00d3D SHIMANO GRX RX410<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">HAMULEC TY\u0141 SHIMANO GRX RX410<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">D\u0179WIGNIE HAMULCA SHIMANO GRX RX610<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">TARCZE HAMULCOWE SHIMANO RT30 160<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">TARCZE HAMULCOWE TY\u0141 SHIMANO RT30 160<\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Komponenty<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">KIEROWNICA ALUMINIUM 31,8 (S, M &#8211; 420MM; L, XL &#8211; 440MM)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">WSPORNIK KIEROWNICY ALUMINIUM 31,8\/7\u00b0 (S, M &#8211; 80MM; L, XL &#8211; 90MM)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">SIOD\u0141O FIZIK TERRA ARGO X5<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">WSPORNIK SIOD\u0141A ALUMINIUM 27,2 (S, M, L &#8211; 350MM; XL &#8211; 400MM)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">STERY FSA ORBIT ACB NO.42 TAPERED<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">CHWYTY KROSS EVA<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">PEDA\u0141Y BRAK<\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">*Producent zastrzega sobie prawo do wprowadzania zmian w dowolnym czasie i bez uprzedzenia, w odniesieniu do wyposa\u017cenia, specyfikacji, modeli, kolor\u00f3w i materia\u0142\u00f3w. Zdj\u0119cia produktu mog\u0105 mie\u0107 charakter pogl\u0105dowy i wygl\u0105d rzeczywisty produktu mo\u017ce si\u0119 nieznacznie r\u00f3\u017cni\u0107.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Sto\u017ckowa g\u0142\u00f3wka ramy o zmiennym przekroju od 1 1\/8&#8243; u g\u00f3ry do 1,5&#8243; u do\u0142u. Wi\u0119ksza \u015brednica na dole daje wi\u0119ksz\u0105 wytrzyma\u0142o\u015b\u0107 oraz sztywno\u015b\u0107 przek\u0142adaj\u0105c\u0105 si\u0119 na precyzj\u0119 w sterowaniu.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wewn\u0119trzne prowadzenie kabli wyd\u0142u\u017ca \u017cywotno\u015b\u0107 linek i pancerzy chroni\u0105c je przed b\u0142otem, piachem czy deszczem.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">W celu maksymalnej ochrony naszych ram stworzyli\u015bmy system wymiennych hak\u00f3w, kt\u00f3re w razie uszkodzenia mo\u017cna \u0142atwo i szybko wymieni\u0107. Aby ograniczy\u0107 mo\u017cliwo\u015b\u0107 uszkodzenia ramy do minimum gwinty umieszczamy na haku lub na specjalnej nakr\u0119tce.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Hamulce tarczowe gwarantuj\u0105 nam du\u017c\u0105 si\u0142\u0119 hamowania i dobr\u0105 modulacj\u0119 nawet w najci\u0119\u017cszych warunkach pogodowych, a ich \u017cywotno\u015b\u0107 jest znacznie d\u0142u\u017csza ni\u017c hamulc\u00f3w tradycyjnych.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Nowy standard mocowania hamulc\u00f3w, kt\u00f3ry pozwala na wi\u0119ksz\u0105 integracj\u0119 zacisku hamulca z ram\u0105 zwi\u0119kszaj\u0105c sztywno\u015b\u0107, obni\u017caj\u0105c mas\u0119 i poprawiaj\u0105c aerodynamik\u0119, co w po\u0142\u0105czeniu z mniejsz\u0105 mas\u0105 pozytywnie wp\u0142ywa na dynamik\u0119 jazdy.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Piasta w standardzie 12&#215;142 mm to sztywno\u015b\u0107 ko\u0142a rodem z rower\u00f3w downhillowych po\u0142\u0105czona z \u0142atwo\u015bci\u0105 monta\u017cu. Usztywnienie to przek\u0142ada si\u0119 na bardziej precyzyjne prowadzenie roweru oraz jego stabilno\u015b\u0107.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2500px;max-height:1875px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/113f76\/6bf931de4c248a0f7e351d37e242\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy\" srcset=\"https:\/\/a.allegroimg.com\/original\/113f76\/6bf931de4c248a0f7e351d37e242\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy 360w,https:\/\/a.allegroimg.com\/original\/113f76\/6bf931de4c248a0f7e351d37e242\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy 720w,https:\/\/a.allegroimg.com\/original\/113f76\/6bf931de4c248a0f7e351d37e242\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy 1024w,https:\/\/a.allegroimg.com\/original\/113f76\/6bf931de4c248a0f7e351d37e242\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy 1440w,https:\/\/a.allegroimg.com\/original\/113f76\/6bf931de4c248a0f7e351d37e242\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy 2500w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2500px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rozmiar:<\/b> XL 22<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Przeznaczenie:<\/b> M\u0119skie Damskie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Kolekcja:<\/b> 2025<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rozmiar k\u00f3\u0142:<\/b> 28&#8243;<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rozmiary ramy:<\/b> XL<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Kolor:<\/b> Bia\u0142y Br\u0105zowy<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Amortyzacja:<\/b> Brak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Hamulce:<\/b> Tarczowe Hydrauliczne<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Materia\u0142 ramy:<\/b> Karbon<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Ilo\u015b\u0107 bieg\u00f3w:<\/b> 12<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Biegi:<\/b> 1&#215;12<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11c2cb\/3277ce804f0d9b6eecab615a401b\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kod-producenta-KREK7Z28X22U008529\" srcset=\"https:\/\/a.allegroimg.com\/original\/11c2cb\/3277ce804f0d9b6eecab615a401b\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kod-producenta-KREK7Z28X22U008529 360w,https:\/\/a.allegroimg.com\/original\/11c2cb\/3277ce804f0d9b6eecab615a401b\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kod-producenta-KREK7Z28X22U008529 720w,https:\/\/a.allegroimg.com\/original\/11c2cb\/3277ce804f0d9b6eecab615a401b\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kod-producenta-KREK7Z28X22U008529 1024w,https:\/\/a.allegroimg.com\/original\/11c2cb\/3277ce804f0d9b6eecab615a401b\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kod-producenta-KREK7Z28X22U008529 1200w,https:\/\/a.allegroimg.com\/original\/11c2cb\/3277ce804f0d9b6eecab615a401b\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kod-producenta-KREK7Z28X22U008529 1200w\" sizes=\"100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Kod producenta KREK7Z28X22U008529\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/113a03\/9a195fc4498dbeae407f1d525625\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Marka-Kross\" srcset=\"https:\/\/a.allegroimg.com\/original\/113a03\/9a195fc4498dbeae407f1d525625\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Marka-Kross 360w,https:\/\/a.allegroimg.com\/original\/113a03\/9a195fc4498dbeae407f1d525625\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Marka-Kross 720w,https:\/\/a.allegroimg.com\/original\/113a03\/9a195fc4498dbeae407f1d525625\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Marka-Kross 1024w,https:\/\/a.allegroimg.com\/original\/113a03\/9a195fc4498dbeae407f1d525625\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Marka-Kross 1200w,https:\/\/a.allegroimg.com\/original\/113a03\/9a195fc4498dbeae407f1d525625\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Marka-Kross 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Marka Kross\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/117d7b\/aa72ea67462aa8cd6db0a96751fb\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Model-Esker-7-0\" srcset=\"https:\/\/a.allegroimg.com\/original\/117d7b\/aa72ea67462aa8cd6db0a96751fb\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Model-Esker-7-0 360w,https:\/\/a.allegroimg.com\/original\/117d7b\/aa72ea67462aa8cd6db0a96751fb\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Model-Esker-7-0 720w,https:\/\/a.allegroimg.com\/original\/117d7b\/aa72ea67462aa8cd6db0a96751fb\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Model-Esker-7-0 1024w,https:\/\/a.allegroimg.com\/original\/117d7b\/aa72ea67462aa8cd6db0a96751fb\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Model-Esker-7-0 1200w,https:\/\/a.allegroimg.com\/original\/117d7b\/aa72ea67462aa8cd6db0a96751fb\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Model-Esker-7-0 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Model Esker 7.0\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/113eb2\/b9324b1a403a88d7922c354599ab\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-ramy-22-cale\" srcset=\"https:\/\/a.allegroimg.com\/original\/113eb2\/b9324b1a403a88d7922c354599ab\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-ramy-22-cale 360w,https:\/\/a.allegroimg.com\/original\/113eb2\/b9324b1a403a88d7922c354599ab\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-ramy-22-cale 720w,https:\/\/a.allegroimg.com\/original\/113eb2\/b9324b1a403a88d7922c354599ab\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-ramy-22-cale 1024w,https:\/\/a.allegroimg.com\/original\/113eb2\/b9324b1a403a88d7922c354599ab\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-ramy-22-cale 1200w,https:\/\/a.allegroimg.com\/original\/113eb2\/b9324b1a403a88d7922c354599ab\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-ramy-22-cale 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Rozmiar ramy 22 cale\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/115d7b\/bff9aaa247e2bb8e7a0c3c6ba22e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-kola-28\" srcset=\"https:\/\/a.allegroimg.com\/original\/115d7b\/bff9aaa247e2bb8e7a0c3c6ba22e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-kola-28 360w,https:\/\/a.allegroimg.com\/original\/115d7b\/bff9aaa247e2bb8e7a0c3c6ba22e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-kola-28 720w,https:\/\/a.allegroimg.com\/original\/115d7b\/bff9aaa247e2bb8e7a0c3c6ba22e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-kola-28 1024w,https:\/\/a.allegroimg.com\/original\/115d7b\/bff9aaa247e2bb8e7a0c3c6ba22e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-kola-28 1200w,https:\/\/a.allegroimg.com\/original\/115d7b\/bff9aaa247e2bb8e7a0c3c6ba22e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Rozmiar-kola-28 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Rozmiar ko\u0142a (&quot;) 28\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11f631\/e6c1aff54551a7339fedf921e4c8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Liczba-biegow-12\" srcset=\"https:\/\/a.allegroimg.com\/original\/11f631\/e6c1aff54551a7339fedf921e4c8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Liczba-biegow-12 360w,https:\/\/a.allegroimg.com\/original\/11f631\/e6c1aff54551a7339fedf921e4c8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Liczba-biegow-12 720w,https:\/\/a.allegroimg.com\/original\/11f631\/e6c1aff54551a7339fedf921e4c8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Liczba-biegow-12 1024w,https:\/\/a.allegroimg.com\/original\/11f631\/e6c1aff54551a7339fedf921e4c8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Liczba-biegow-12 1200w,https:\/\/a.allegroimg.com\/original\/11f631\/e6c1aff54551a7339fedf921e4c8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Liczba-biegow-12 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Liczba bieg\u00f3w 12\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/1161ad\/a96595054758bd232508b66fbcc6\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kolor-bialy\" srcset=\"https:\/\/a.allegroimg.com\/original\/1161ad\/a96595054758bd232508b66fbcc6\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kolor-bialy 360w,https:\/\/a.allegroimg.com\/original\/1161ad\/a96595054758bd232508b66fbcc6\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kolor-bialy 720w,https:\/\/a.allegroimg.com\/original\/1161ad\/a96595054758bd232508b66fbcc6\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kolor-bialy 1024w,https:\/\/a.allegroimg.com\/original\/1161ad\/a96595054758bd232508b66fbcc6\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kolor-bialy 1200w,https:\/\/a.allegroimg.com\/original\/1161ad\/a96595054758bd232508b66fbcc6\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Kolor-bialy 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Kolor bia\u0142y\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/1128c6\/79bf66614903864b01b3028a9d3f\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Material-ramy-karbon\" srcset=\"https:\/\/a.allegroimg.com\/original\/1128c6\/79bf66614903864b01b3028a9d3f\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Material-ramy-karbon 360w,https:\/\/a.allegroimg.com\/original\/1128c6\/79bf66614903864b01b3028a9d3f\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Material-ramy-karbon 720w,https:\/\/a.allegroimg.com\/original\/1128c6\/79bf66614903864b01b3028a9d3f\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Material-ramy-karbon 1024w,https:\/\/a.allegroimg.com\/original\/1128c6\/79bf66614903864b01b3028a9d3f\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Material-ramy-karbon 1200w,https:\/\/a.allegroimg.com\/original\/1128c6\/79bf66614903864b01b3028a9d3f\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Material-ramy-karbon 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Materia\u0142 ramy karbon\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11497c\/4d7c515e43a6aab864303118c140\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Plec-produkt-uniseks\" srcset=\"https:\/\/a.allegroimg.com\/original\/11497c\/4d7c515e43a6aab864303118c140\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Plec-produkt-uniseks 360w,https:\/\/a.allegroimg.com\/original\/11497c\/4d7c515e43a6aab864303118c140\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Plec-produkt-uniseks 720w,https:\/\/a.allegroimg.com\/original\/11497c\/4d7c515e43a6aab864303118c140\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Plec-produkt-uniseks 1024w,https:\/\/a.allegroimg.com\/original\/11497c\/4d7c515e43a6aab864303118c140\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Plec-produkt-uniseks 1200w,https:\/\/a.allegroimg.com\/original\/11497c\/4d7c515e43a6aab864303118c140\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Plec-produkt-uniseks 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy P\u0142e\u0107 produkt uniseks\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:700px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/1103f0\/6cbec3814c5a95f0b5f8c2ddae31\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Wzrost-uzytkownika-184-194-cm\" srcset=\"https:\/\/a.allegroimg.com\/original\/1103f0\/6cbec3814c5a95f0b5f8c2ddae31\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Wzrost-uzytkownika-184-194-cm 360w,https:\/\/a.allegroimg.com\/original\/1103f0\/6cbec3814c5a95f0b5f8c2ddae31\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Wzrost-uzytkownika-184-194-cm 720w,https:\/\/a.allegroimg.com\/original\/1103f0\/6cbec3814c5a95f0b5f8c2ddae31\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Wzrost-uzytkownika-184-194-cm 1024w,https:\/\/a.allegroimg.com\/original\/1103f0\/6cbec3814c5a95f0b5f8c2ddae31\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Wzrost-uzytkownika-184-194-cm 1200w,https:\/\/a.allegroimg.com\/original\/1103f0\/6cbec3814c5a95f0b5f8c2ddae31\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Wzrost-uzytkownika-184-194-cm 1200w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1200px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Wzrost u\u017cytkownika 184-194 cm\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:777px;max-height:601px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/119c82\/c650e30b40c0b4b059e413c826d8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany\" srcset=\"https:\/\/a.allegroimg.com\/original\/119c82\/c650e30b40c0b4b059e413c826d8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 360w,https:\/\/a.allegroimg.com\/original\/119c82\/c650e30b40c0b4b059e413c826d8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 720w,https:\/\/a.allegroimg.com\/original\/119c82\/c650e30b40c0b4b059e413c826d8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 777w,https:\/\/a.allegroimg.com\/original\/119c82\/c650e30b40c0b4b059e413c826d8\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 777w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"777px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Stopie\u0144 z\u0142o\u017cenia wst\u0119pnie z\u0142o\u017cony, wyregulowany\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1222px;max-height:763px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/117816\/e3f1d78f4f63aa764c694aa02f9e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Hamulce-tarczowe-hydrauliczne\" srcset=\"https:\/\/a.allegroimg.com\/original\/117816\/e3f1d78f4f63aa764c694aa02f9e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Hamulce-tarczowe-hydrauliczne 360w,https:\/\/a.allegroimg.com\/original\/117816\/e3f1d78f4f63aa764c694aa02f9e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Hamulce-tarczowe-hydrauliczne 720w,https:\/\/a.allegroimg.com\/original\/117816\/e3f1d78f4f63aa764c694aa02f9e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Hamulce-tarczowe-hydrauliczne 1024w,https:\/\/a.allegroimg.com\/original\/117816\/e3f1d78f4f63aa764c694aa02f9e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Hamulce-tarczowe-hydrauliczne 1222w,https:\/\/a.allegroimg.com\/original\/117816\/e3f1d78f4f63aa764c694aa02f9e\/Kross-Esker-7-0-rozmiar-XL-22-bialy-perlowy-Hamulce-tarczowe-hydrauliczne 1222w\" sizes=\"100vw\" width=\"1222px\" alt=\"Kross Esker 7.0 rozmiar XL 22&amp;quot; bia\u0142y per\u0142owy Hamulce tarczowe hydrauliczne\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Producent &#8211;&nbsp;<b>KROSS S.A.<\/b>&nbsp;udziela na zakupiony rower gwarancji jako\u015bci na okres 2 lat, licz\u0105c od daty zakupu.&nbsp;Warunkiem obowi\u0105zywania Gwarancji jest dokonanie p\u0142atnych przegl\u0105d\u00f3w: pierwszego w terminie mi\u0119dzy 30. a 60. dniem od daty zakupu (dla rower\u00f3w zakupionych w miesi\u0105cach od listopada do ko\u0144ca stycznia przegl\u0105d mo\u017ce by\u0107 wykonany najp\u00f3\u017aniej do dnia 31 marca), przegl\u0105du okresowego pomi\u0119dzy 11. a 16. miesi\u0105cem od daty zakupu. Przegl\u0105d mo\u017ce zosta\u0107 wykonany w autoryzowanych punktach serwisowych lub punktach sprzeda\u017cy Kross.<\/li>\n<\/ul>\n<h2>Rama to najwa\u017cniejsza cz\u0119\u015b\u0107 roweru, od niej zale\u017cy charakter, bezpiecze\u0144stwo i komfort jazdy<\/h2>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Producent- firma&nbsp;<b>KROSS S.A<\/b>. daje mo\u017cliwo\u015b\u0107 uzyskania&nbsp;<b>do\u017cywotniej ochrony<\/b>&nbsp;na ramy stalowe i aluminiowe oraz ramy full suspension i carbon na 5 lat!<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Aby uzyska\u0107 Przed\u0142u\u017con\u0105 Ochron\u0119 nale\u017cy w terminie 30 dni od daty zakupu zarejestrowa\u0107 si\u0119 na stronie KROSSa i doda\u0107 zakupiony rower wype\u0142niaj\u0105c odpowiedni formularz.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">WA\u017bNE! Przed\u0142u\u017cona Ochrona obejmuje konstrukcj\u0119 ramy. Warstwa lakiernicza oraz oklejenie ramy nie s\u0105 obj\u0119te Przed\u0142u\u017con\u0105 Ochron\u0105.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n","protected":false},"excerpt":{"rendered":"<p>Rower Gravel Kross Esker 7.0 Per\u0142owy\/Br\u0105zowy Po\u0142ysk &#8211; XL 22<\/p>\n<p>Kross<\/p>\n<p>Rowery gravelowe Kross to wszechstronne jedno\u015blady stworzone do pokonywania zar\u00f3wno asfaltowych dr\u00f3g, jak i trudniejszych nawierzchni terenowych. Dzi\u0119ki specjalnie zaprojektowanym ramom gravele Kross \u0142\u0105cz\u0105 komfort jazdy na d\u0142u\u017cszych trasach z mo\u017cliwo\u015bci\u0105 eksploracji mniej utwardzonych \u015bcie\u017cek, zapewniaj\u0105c rowerzystom wyj\u0105tkow\u0105 swobod\u0119 i dostosowanie do r\u00f3\u017cnorodnych warunk\u00f3w.<\/p>\n<p>KROSS ESKER 7.0<\/p>\n","protected":false},"featured_media":14277,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[692],"product_cat":[702,688,687],"product_tag":[],"class_list":{"0":"post-14276","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-kross","7":"product_cat-przelajowe-gravel","8":"product_cat-rowery","9":"product_cat-rowery-i-akcesoria","11":"first","12":"instock","13":"sale","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276.jpg",2500,1875,false],"thumbnail":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-150x150.jpg",150,150,true],"medium":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-300x225.jpg",300,225,true],"medium_large":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-768x576.jpg",768,576,true],"large":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-1536x1152.jpg",1536,1152,true],"2048x2048":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-2048x1536.jpg",2048,1536,true],"woocommerce_thumbnail":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-600x450.jpg",600,450,true],"woocommerce_gallery_thumbnail":["https:\/\/xavlino.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14276-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/xavlino.shop\/ro64\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Rower Gravel Kross Esker 7.0 Per\u0142owy\/Br\u0105zowy Po\u0142ysk - XL 22 Kross Rowery gravelowe Kross to wszechstronne jedno\u015blady stworzone do pokonywania zar\u00f3wno asfaltowych dr\u00f3g, jak i trudniejszych nawierzchni terenowych. Dzi\u0119ki specjalnie zaprojektowanym ramom gravele Kross \u0142\u0105cz\u0105 komfort jazdy na d\u0142u\u017cszych trasach z mo\u017cliwo\u015bci\u0105 eksploracji mniej utwardzonych \u015bcie\u017cek, zapewniaj\u0105c rowerzystom wyj\u0105tkow\u0105 swobod\u0119 i dostosowanie do r\u00f3\u017cnorodnych warunk\u00f3w.&hellip;","_links":{"self":[{"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/product\/14276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/media\/14277"}],"wp:attachment":[{"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/media?parent=14276"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/product_brand?post=14276"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/product_cat?post=14276"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xavlino.shop\/ro64\/wp-json\/wp\/v2\/product_tag?post=14276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}